{"id":13298,"date":"2024-04-25T12:18:50","date_gmt":"2024-04-25T10:18:50","guid":{"rendered":"https:\/\/prague.org\/?p=13298"},"modified":"2024-04-30T10:29:58","modified_gmt":"2024-04-30T08:29:58","slug":"celebrar-o-dia-1-de-maio-nas-tradicoes-da-republica-checa","status":"publish","type":"post","link":"https:\/\/prague.org\/pt\/celebrating-may-1st-in-the-czech-republic-traditions\/","title":{"rendered":"Celebrar o 1\u00ba de maio na Rep\u00fablica Checa: Tradi\u00e7\u00f5es e impacto cultural"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>1 de maio na Rep\u00fablica Checa<\/strong> \u00e9 comemorado com grande zelo e entusiasmo como Dia do Trabalhador (Sv\u00e1tek pr\u00e1ce), um importante feriado nacional. O Dia do Trabalhador \u00e9 culturalmente significativo porque \u00e9 um momento de conv\u00edvio social, introspe\u00e7\u00e3o e campanha pelos direitos dos trabalhadores; para al\u00e9m disso, honra o movimento laboral e as conquistas dos trabalhadores. Venha connosco mergulhar no significado cultural e nas tradi\u00e7\u00f5es do<strong> 1 de maio na Rep\u00fablica Checa<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, o dia 1 de maio est\u00e1 tamb\u00e9m ligado a antigas festividades pag\u00e3s. Este dia marcava o in\u00edcio da planta\u00e7\u00e3o da primavera e as pessoas dan\u00e7avam \u00e0 volta do mastro de maio para comemorar a fertilidade da terra. A oferta de l\u00edrios do vale e a queima de bruxas no dia 1 de maio s\u00e3o outros costumes e rituais checos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Muitas coisas acontecem no dia 1 de maio na cultura e na pol\u00edtica checas. Atualmente, comemora os trabalhadores, incentiva a mudan\u00e7a social e une as comunidades para celebrar a primavera e o esp\u00edrito humano. Reserve um minuto para refletir sobre a import\u00e2ncia do 1.\u00ba de maio na cultura e na hist\u00f3ria da Rep\u00fablica Checa, quer opte por dan\u00e7ar \u00e0 volta de um mastro ou por marchar numa manifesta\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<h2 id=\"the-origins-and-traditions-of-may-1st-as-a-czech-national-holiday\" class=\"wp-block-heading\">As origens e as tradi\u00e7\u00f5es do 1\u00ba de maio como feriado nacional checo<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O movimento oper\u00e1rio mundial e a luta pelos direitos dos trabalhadores est\u00e3o desde h\u00e1 muito ligados ao 1\u00ba de maio. A data foi escolhida para homenagear o acontecimento de Haymarket, uma greve de trabalhadores por um dia de trabalho de oito horas que teve lugar em Chicago em 1886. V\u00e1rias pessoas foram feridas ou mortas em resultado das violentas lutas que eclodiram entre os trabalhadores e a pol\u00edcia durante as manifesta\u00e7\u00f5es. Em reconhecimento da luta dos trabalhadores pela justi\u00e7a social e pela melhoria das condi\u00e7\u00f5es de trabalho, a Confer\u00eancia Internacional Socialista criou <strong>1 de maio na Rep\u00fablica Checa<\/strong> como Dia Internacional dos Trabalhadores em 1889.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com a funda\u00e7\u00e3o do <a href=\"https:\/\/prague.org\/pt\/republica-checa-comunismo\/\">Primeira Rep\u00fablica da Checoslov\u00e1quia em 1918<\/a>Na Checoslov\u00e1quia, o dia 1 de maio foi declarado feriado oficial. O dia 1 de maio foi formalmente institu\u00eddo como Dia do Trabalhador pelo novo governo, chefiado pelo Partido Social Democrata. Esta decis\u00e3o foi tomada em reconhecimento do valor das contribui\u00e7\u00f5es dos trabalhadores para a sociedade. Os activistas dos direitos dos trabalhadores celebraram o evento para recordar aqueles que tinham lutado contra a explora\u00e7\u00e3o e a desigualdade e as dificuldades que tinham suportado.<\/p>\n\n\n\n<h2 id=\"events-and-festivities-on-may-1st-across-the-czech-republic\" class=\"wp-block-heading\">Eventos e festividades do dia 1 de maio em toda a Rep\u00fablica Checa<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Em comemora\u00e7\u00e3o do Dia do Trabalhador (Sv\u00e1tek pr\u00e1ce) em<strong> 1 de maio, feriado nacional<\/strong>Em toda a Rep\u00fablica Checa, realizam-se celebra\u00e7\u00f5es que homenageiam o movimento oper\u00e1rio e os contributos dos trabalhadores. Nestas celebra\u00e7\u00f5es, \u00e9 poss\u00edvel participar em eventos culturais, encontros sociais e manifesta\u00e7\u00f5es em defesa dos direitos dos trabalhadores. Em <strong>1 de maio, Rep\u00fablica Checa<\/strong> tem normalmente as seguintes celebra\u00e7\u00f5es:<\/p>\n\n\n\n<h3 id=\"parades-and-protests\" class=\"wp-block-heading\">Desfiles e protestos<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Os trabalhadores e as organiza\u00e7\u00f5es sindicais da Rep\u00fablica Checa organizam marchas, com\u00edcios e manifesta\u00e7\u00f5es em muitas cidades para exigir melhores condi\u00e7\u00f5es de trabalho, mais igualdade econ\u00f3mica e justi\u00e7a social. Os manifestantes desfilam pelas ruas com cartazes, bandeiras e faixas que mostram as posi\u00e7\u00f5es e os objectivos dos seus grupos. Nestas manifesta\u00e7\u00f5es, os trabalhadores podem expressar as suas preocupa\u00e7\u00f5es e exigir melhores condi\u00e7\u00f5es de trabalho.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/prague.org\/wp-content\/uploads\/2024\/04\/anthony-delanoix-aDxmYZtYj7g-unsplash-1-1024x683.jpg\" alt=\"\" class=\"wp-image-13302\" srcset=\"https:\/\/prague.org\/wp-content\/uploads\/2024\/04\/anthony-delanoix-aDxmYZtYj7g-unsplash-1-1024x683.jpg 1024w, https:\/\/prague.org\/wp-content\/uploads\/2024\/04\/anthony-delanoix-aDxmYZtYj7g-unsplash-1-300x200.jpg 300w, https:\/\/prague.org\/wp-content\/uploads\/2024\/04\/anthony-delanoix-aDxmYZtYj7g-unsplash-1-768x512.jpg 768w, https:\/\/prague.org\/wp-content\/uploads\/2024\/04\/anthony-delanoix-aDxmYZtYj7g-unsplash-1-1536x1024.jpg 1536w, https:\/\/prague.org\/wp-content\/uploads\/2024\/04\/anthony-delanoix-aDxmYZtYj7g-unsplash-1-2048x1365.jpg 2048w, https:\/\/prague.org\/wp-content\/uploads\/2024\/04\/anthony-delanoix-aDxmYZtYj7g-unsplash-1-18x12.jpg 18w, https:\/\/prague.org\/wp-content\/uploads\/2024\/04\/anthony-delanoix-aDxmYZtYj7g-unsplash-1-380x253.jpg 380w, https:\/\/prague.org\/wp-content\/uploads\/2024\/04\/anthony-delanoix-aDxmYZtYj7g-unsplash-1-800x533.jpg 800w, https:\/\/prague.org\/wp-content\/uploads\/2024\/04\/anthony-delanoix-aDxmYZtYj7g-unsplash-1-1160x773.jpg 1160w, https:\/\/prague.org\/wp-content\/uploads\/2024\/04\/anthony-delanoix-aDxmYZtYj7g-unsplash-1-600x400.jpg 600w, https:\/\/prague.org\/wp-content\/uploads\/2024\/04\/anthony-delanoix-aDxmYZtYj7g-unsplash-1-scaled.jpg 2560w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Ponte Carlos <\/figcaption><\/figure>\n\n\n\n<h3 id=\"cultural-performances\" class=\"wp-block-heading\">Espect\u00e1culos culturais<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Os parques p\u00fablicos, as pra\u00e7as e os centros culturais acolhem frequentemente espect\u00e1culos musicais, de dan\u00e7a e teatrais no dia 1 de maio, no \u00e2mbito de eventos culturais. Os artistas e int\u00e9rpretes participantes da regi\u00e3o ir\u00e3o deliciar os convidados com uma variedade de espect\u00e1culos tem\u00e1ticos do Dia do Trabalhador, incluindo pe\u00e7as cl\u00e1ssicas e modernas.<\/p>\n\n\n\n<h3 id=\"enjoying-the-outdoors\" class=\"wp-block-heading\">Desfrutar do ar livre<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Neste <a href=\"https:\/\/prague.org\/pt\/czech-republic-public-holidays\/\" data-type=\"link\" data-id=\"https:\/\/prague.org\/czech-republic-public-holidays\/\">F\u00e9rias na Rep\u00fablica Checa<\/a>No dia 15 de junho, muitos habitantes locais e visitantes re\u00fanem-se em parques e outras \u00e1reas abertas para piqueniques, concertos e outras formas de entretenimento ao ar livre. Em honra das vit\u00f3rias do movimento oper\u00e1rio, \u00e9 uma altura para descontrair, celebrar com amigos e fam\u00edlia e desfrutar de algum tempo de descanso.<\/p>\n\n\n\n<h3 id=\"labour-themed-exhibitions-and-workshops\" class=\"wp-block-heading\">Exposi\u00e7\u00f5es e workshops sobre temas laborais<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Os museus, galerias e outros centros culturais organizam frequentemente workshops, exposi\u00e7\u00f5es especiais e programas educativos que se centram no movimento laboral na Rep\u00fablica Checa e na sua hist\u00f3ria e import\u00e2ncia. Estes eventos mostram como as preocupa\u00e7\u00f5es laborais ainda s\u00e3o relevantes na sociedade atual e lan\u00e7am luz sobre as dificuldades e vit\u00f3rias dos trabalhadores checos ao longo da hist\u00f3ria.<\/p>\n\n\n\n<h3 id=\"advocacy-for-social-and-political-change\" class=\"wp-block-heading\">Defesa da mudan\u00e7a social e pol\u00edtica<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Grupos e indiv\u00edduos utilizam o feriado do Primeiro de maio para chamar a aten\u00e7\u00e3o para quest\u00f5es como a desigualdade econ\u00f3mica, a justi\u00e7a social e os direitos dos trabalhadores. Reuni\u00f5es como f\u00f3runs p\u00fablicos, debates e campanhas de sensibiliza\u00e7\u00e3o juntam as pessoas para terem conversas importantes e trabalharem em prol de uma sociedade melhor.<\/p>\n\n\n\n<h2 id=\"the-role-of-may-1st-in-czech-culture-and-public-life\" class=\"wp-block-heading\">O papel do 1\u00ba de maio na cultura e na vida p\u00fablica da Rep\u00fablica Checa<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O Primeiro de maio \u00e9 um dia \u00fanico na cultura e na vida p\u00fablica da Rep\u00fablica Checa, pois comemora os trabalhadores, os direitos laborais e a primavera. O Dia do Trabalhador na Rep\u00fablica Checa tem uma longa hist\u00f3ria de cerim\u00f3nias de constru\u00e7\u00e3o da comunidade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O mastro de maio, ou \"m\u00e1jka\", \u00e9 um ritual checo popular no dia 1 de maio, enfeitado com fitas, flores e outras decora\u00e7\u00f5es nas pra\u00e7as das cidades. Dan\u00e7as, c\u00e2nticos e festejos acompanham o mastro de maio, que simboliza a fertilidade e a primavera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Juntamente com o mastro, <strong>1 de maio na Rep\u00fablica Checa<\/strong> \u00e9 um dia de luta pol\u00edtica e social na Rep\u00fablica Checa. Os sindicatos e os trabalhadores organizam protestos para exigir melhores condi\u00e7\u00f5es de trabalho, sal\u00e1rios e direitos laborais. A hist\u00f3ria do trabalho e da justi\u00e7a social do pa\u00eds reflecte-se no dia 1 de maio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em geral,<strong> O dia 1 de maio \u00e9 um feriado banc\u00e1rio<\/strong> e um dia de festa, demonstra\u00e7\u00f5es e descontra\u00e7\u00e3o. Os checos aproveitam o feriado para dedicar tempo \u00e0 fam\u00edlia e aos amigos, desfrutar de aventuras ao ar livre e comer e beber iguarias tradicionais checas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"O dia 1 de maio na Rep\u00fablica Checa \u00e9 comemorado com grande zelo e entusiasmo como o Dia do Trabalhador (Sv\u00e1tek pr\u00e1ce),...","protected":false},"author":19,"featured_media":13303,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,15,204,39,47,46],"tags":[49],"class_list":["post-13298","post","type-post","status-publish","format-standard","has-post-thumbnail","category-what-to-do-and-see","category-basic-prague-info","category-blog","category-culture","category-guides-what-to-do-and-see","category-traveler-ressources","tag-culture","cs-entry","cs-video-wrap"],"_links":{"self":[{"href":"https:\/\/prague.org\/pt\/wp-json\/wp\/v2\/posts\/13298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prague.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prague.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prague.org\/pt\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/prague.org\/pt\/wp-json\/wp\/v2\/comments?post=13298"}],"version-history":[{"count":2,"href":"https:\/\/prague.org\/pt\/wp-json\/wp\/v2\/posts\/13298\/revisions"}],"predecessor-version":[{"id":13310,"href":"https:\/\/prague.org\/pt\/wp-json\/wp\/v2\/posts\/13298\/revisions\/13310"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prague.org\/pt\/wp-json\/wp\/v2\/media\/13303"}],"wp:attachment":[{"href":"https:\/\/prague.org\/pt\/wp-json\/wp\/v2\/media?parent=13298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prague.org\/pt\/wp-json\/wp\/v2\/categories?post=13298"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prague.org\/pt\/wp-json\/wp\/v2\/tags?post=13298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}